{"id":17,"count":46,"description":"Per\u00adch\u00e9 si accen\u00adde solo una del\u00adle lam\u00adpa\u00addi\u00adne? Per\u00adch\u00e9 \u00e8 l\u2019unica col\u00adle\u00adga\u00adta alla fon\u00adte di ener\u00adgia! Una lam\u00adpa\u00addi\u00adna non ha in s\u00e9 la for\u00adza di illu\u00admi\u00adna\u00adre.\n\nAllo stes\u00adso modo, una per\u00adso\u00adna deve esse\u00adre col\u00adle\u00adga\u00adta alla fon\u00adte \u2013 il Crea\u00adto\u00adre del\u00adla vita \u2013 per illu\u00admi\u00adna\u00adre ci\u00f2 che la cir\u00adcon\u00adda. In ques\u00adto modo, l\u2019essenza di Dio, il suo amo\u00adre e la sua gioia, si mani\u00adfest\u00ada\u00adno ovun\u00adque nella vita di tut\u00adti i gior\u00adni e  rega\u00adla\u00adno spe\u00adran\u00adza. \u00c8 pro\u00adprio ques\u00adta la nos\u00adt\u00adra mis\u00adsio\u00adne!\n\nNon si trat\u00adta inn\u00adan\u00adzi\u00adtutto di anda\u00adre in Paradi\u00adso, ma di far scen\u00adde\u00adre il Paradi\u00adso sul\u00adla ter\u00adra attra\u00adver\u00adso di noi. Come pu\u00f2 suc\u00adce\u00adde\u00adre? Attra\u00adver\u00adso la tua dis\u00adpo\u00adni\u00adbi\u00adli\u00adt\u00e0 a guar\u00adda\u00adre Dio, per poi risple\u00adnde\u00adre in ques\u00adto&nbsp;mondo!","link":"https:\/\/sermons.seetal-chile.ch\/it\/series\/glow\/","name":"baglio\u00adre","slug":"glow","taxonomy":"wpfc_sermon_series","meta":[],"acf":[],"sermons_taxonomy_image":"https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2018\/10\/Serie_glow.jpg","sermons_taxonomy_description":"Warum leuchtet nur eine der Gl\u00fchbirnen? Weil nur sie an der Stromquelle angeschlossen ist! Eine Gl\u00fchbirne tr\u00e4gt die Kraft zum Leuchten nicht in sich selbst....","_links":{"self":[{"href":"https:\/\/sermons.seetal-chile.ch\/it\/wp-json\/wp\/v2\/wpfc_sermon_series\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sermons.seetal-chile.ch\/it\/wp-json\/wp\/v2\/wpfc_sermon_series"}],"about":[{"href":"https:\/\/sermons.seetal-chile.ch\/it\/wp-json\/wp\/v2\/taxonomies\/wpfc_sermon_series"}],"wp:post_type":[{"href":"https:\/\/sermons.seetal-chile.ch\/it\/wp-json\/wp\/v2\/wpfc_sermon?wpfc_sermon_series=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}