{"id":7170,"date":"2023-02-12T08:45:48","date_gmt":"2023-02-12T07:45:48","guid":{"rendered":"https:\/\/sermons.seetal-chile.ch\/?post_type=wpfc_sermon&#038;p=7170"},"modified":"2025-10-28T08:14:32","modified_gmt":"2025-10-28T07:14:32","slug":"furchteinfloessende-heiligkeit","status":"publish","type":"wpfc_sermon","link":"https:\/\/sermons.seetal-chile.ch\/fr\/sermons\/furchteinfloessende-heiligkeit\/","title":{"rendered":"Une sain\u00adte\u00adt\u00e9 qui fait&nbsp;peur"},"content":{"rendered":"<p>Wir k\u00f6nnen die Begegnungen mit dem heiligen Gott nicht erzwingen. Wenn wir ihm aber begegnen, dann kann dies mitunter furchteinfl\u00f6ssend sein. Dennoch m\u00fcssen wir uns aber vor diesem Gott nicht f\u00fcrchten. Denn wenn wir diese Furcht richtig benutzen, dann f\u00fchrt sie uns in Gottesfurcht. Diese wiederum f\u00fchrt uns zu einem Gottesdienst in Ehrfurcht, so wie es einem heiligen Gott geb\u00fchrt.<\/p>\n<p>Vor kurzem hatte ich ein Gespr\u00e4ch mit einer Person \u00fcber den diesj\u00e4hrigen Teaser zum Jahresthema. Diese Person \u00e4usserte sich grunds\u00e4tzlich positiv \u00fcber den Teaser, allerdings haben ihr mindestens die beiden vorherigen besser entsprochen. Als ich nach dem Grund fragte, kam diese Antwort. Sie waren weniger furchteinfl\u00f6ssend!<br \/>\nBegegnungen mit Gott kann ich nicht erzwingen<br \/>\nHeilig, heilig, heilig &#8211; Begegnung mit dem ganz Anderen. Dies ist unser diesj\u00e4hriges Jahresthema. Wenn etwas heilig ist, dann ist es auch ganz anders. Heute wollen wir gemeinsam in eine Geschichte einsteigen, bei dem eine Gottesbegegnung ein gesamtes Leben auf den Kopf stellte. Es ist eine der ersten Gottesbegegnungen. Wir finden diese im ersten Buch Mose im Kapitel 28. Es ist die Geschichte von Jakob. Jakob lebt in der dritten Generation der Familie, welche sich Gott f\u00fcr seine Geschichte auf dieser Erde ausgesucht hat. Gott hat sich diese Familie nicht ausgesucht, weil sie heilig waren. Er hat sich diese Familie nicht ausgesucht, weil immer alles rund lief oder sie immer alles so machten wie sie sollten. Er hat sich diese Familie auserw\u00e4hlt, weil sie ihr Vertrauen immer wieder auf Gott setzten. Nur so ist es verst\u00e4ndlich, weshalb Jakob in den biblischen Geschichten nicht nur positiv wegkommt, sondern teilweise auch sehr schlecht. Die Geschichten erz\u00e4hlen von den tiefsten Tiefen menschlichen Lebens.<br \/>\nJakob hatte einen Zwillingsbruder namens Esau. Zu damaliger Zeit war es wichtig, der erstgeborene Sohn zu sein. Denn diesem stand der Grossteil des Erbes zu und er stand in besonderer Gunst seines Vaters. Jakob war der Zweitgeborene. Doch er tat so einiges, um diesen Zustand umzudrehen. Denn schliesslich h\u00e4tte ja auch er der Erstgeborene werden k\u00f6nnen. So erpresste er in einer g\u00fcnstigen Situation seinen Bruder um sein Erstgeburtsrecht. D.h. um den Grossteil des Erbes. Doch dem nicht genug. Als sein Vater Esau segnen wollte, erschlich sich Jakob den Segen seines blinden Vaters. Dies sogar noch mithilfe seiner Mutter. Verst\u00e4ndlicherweise war sein Bruder Esau w\u00fctend und trachtete ihm nach dem Leben. Daher flieht Jakob in das Land seiner Mutter. Unterwegs legt er sich schlafen und als Kissen nimmt er einen Stein. Um dieses Ereignis dort bei diesem Schlafplatz dreht sich die heutige Predigt.<br \/>\nAls nun Jakob dort schlief, fing er an zu tr\u00e4umen. In diesem Traum sah er eine Leiter vom Erdboden bis zum Himmel hinauf. Auf dieser Leiter gingen die Engel Gottes hinauf und herunter. Ganz oben auf der Leiter im Himmel stand Gott und sprach: \u00ab [\u2026] Ich bin der HERR, der Gott deines Grossvaters Abraham und der Gott deines Vaters Isaak. Das Land, auf dem du liegst, werde ich deinen Nachkommen geben. Deine Nachkommen werden so zahlreich sein wie der Staub der Erde. Sie werden sich ausbreiten nach Osten, Westen, Norden und S\u00fcden. Durch dich und deine Nachkommen sollen alle Sippen der Erde gesegnet werden. Mehr noch, ich werde bei dir sein und dich besch\u00fctzen, wo du auch hingehst. Ich werde dich in dieses Land zur\u00fcckbringen. Ich werde dich nie im Stich lassen und stehe zu meinen Zusagen, die ich dir gegeben habe\u00bb (1. Mose 28,13-15 NLB).<br \/>\nDiese Begegnung mit Gott ist exemplarisch f\u00fcr das Wirken Gottes und sein Reden. Denn Gott begegnet Jakob in seiner wohl schw\u00e4chsten Stunde. Jakob begegnet Gott in seiner Schw\u00e4che. Dies ist bis heute h\u00e4ufig so. Wenn alles, was dem Menschen bisher vermeintlich Halt gab, wegbricht, ist er offener f\u00fcr Begegnungen mit dem G\u00f6ttlichen. Solange alles rundl\u00e4uft, vertraut man auf anderes bspw. die finanzielle Unabh\u00e4ngigkeit, Familie &amp; Freunde, seine Gesundheit oder auf sonstige Dinge. Erst wenn alles wegbricht, merkt man h\u00e4ufig, wie wichtig sie einem waren. Und wie fl\u00fcchtig das Ganze ist. H\u00e4ufig kommt der Vorwurf, dass sich Menschen nur f\u00fcr Gott interessieren, weil sie schwach sind. Doch vielleicht k\u00f6nnte man vielmehr sagen, dass sich die Menschen dann f\u00fcr Gott interessieren, wenn sie merken, dass sie schlussendlich nichts mitnehmen k\u00f6nnen, wenn sie einmal sterben.<br \/>\nIch m\u00f6chte hier kurz einen Exkurs einf\u00fcgen zu den Segnungen, welche Gott den Menschen zuteilwerden l\u00e4sst. Gott begegnet Jakob zwar in seiner Schw\u00e4che, verheisst ihm aber einiges. Denn im Alten Testament sind die Segnungen immer auch mit irdischen Dingen verbunden. Doch dieser Fokus ist im Neuen Testament anders gelegt. Die irdische Familie, Partner und Kinder, sowie irdischer Besitz werden nicht mehr als Mittelpunkt der g\u00f6ttlichen Segnungen angesehen. Dies zeigt sich insbesondere deutlich an Paulus. Dieser war der gr\u00f6sste Kirchengr\u00fcnder seiner Zeit und massgebend f\u00fcr die Theologie. Er selbst lebte alleinstehend und propagierte dies als den erstrebenswertesten Zustand als Nachfolger von Jesus Christus. Dies wird heute schnell vergessen. Geh\u00f6rt es doch indirekt zum Bild, dass die Nachfolger von Jesus Christus verheiratet sind und mindestens drei Kinder haben. Aber Paulus malt ein ganz anderes Bild. Denn anstatt der Verheissung von vielen Kindern und viel Besitz ruft Paulus zum Verzicht von Familie und Kindern auf zum Wohl des Reiches Gottes. Denn Jesus sagte: \u00ab[\u2026] Wer ist meine Mutter? Wer sind meine Br\u00fcder? [\u2026] Diese Leute hier sind meine Mutter und meine Br\u00fcder. Wer den Willen Gottes tut, ist mein Bruder und meine Schwester und meine Mutter\u00bb (Markus 3,33-35 NLB). Verzicht auf einen irdischen Partner bedeutet nicht auf eine Familie zu verzichten. Denn wir als Kirche sind eine Familie. Denn diese Einstellung von Paulus gr\u00fcndet sich auf der Tatsache, dass das Reich Gottes unsere wichtigste Angelegenheit sein soll (Matth\u00e4us 6,33). Wenn man nun also verheiratet ist und Kinder hat, dann kann dies schneller aus den Augen verloren werden, als wenn man allein bleibt f\u00fcr das Reich Gottes.<br \/>\nDie Begegnung mit dem Gott der Bibel ist furchteinfl\u00f6ssend!<br \/>\nBist du bereit Gott in diesem Jahr zu begegnen? Dem Gott, welcher ganz anders ist? Doch eines zeigt uns die Geschichte Jakobs auch noch. Die Begegnung mit Gott ist unverf\u00fcgbar, wir k\u00f6nnen sie nicht heraufbezwingen. So ist es auch mit jedem Gottesdienst. Es ist ein Zusammenkommen der Nachfolger von Jesus Christus, mit der festen Zuversicht, dass Gott sich der versammelten Gemeinschaft zeigt. Aber die Begegnung Gottes ist etwas, was er uns schenken muss. Wir d\u00fcrfen aber in grosser Erwartungshaltung kommen, dass er uns begegnen will.<br \/>\nDoch wie reagierte Jakob auf diese Begegnung? \u00abAls nun Jakob von seinem Schlaf aufwachte, sprach er: F\u00fcrwahr, der HERR ist an dieser St\u00e4tte, und ich wusste es nicht! Und er f\u00fcrchtete sich und sprach: Wie heilig ist diese St\u00e4tte! Hier ist nichts anderes als Gottes Haus, und hier ist die Pforte des Himmels\u00bb (1. Mose 28,16-17 LUT). Jakob war ganz erstaunt, dass Gott an diesem Ort war. Ich denke, dass es seine erste Gottesbegegnung war und er ihn nur vom H\u00f6rensagen und von der Fr\u00f6mmigkeit seines Vaters kannte. Die Aus\u00fcbung des Glaubens war f\u00fcr ihn bisher vielmehr Tradition. Es war kein Ausdruck einer tiefen Beziehung und \u00dcberzeugung. Doch von nun an beschliesst er sein Vertrauen ganz auf ihn zu setzen. Wie sieht es bei dir aus? Kennst du Gott so wie Jakob nur vom H\u00f6rensagen oder der Fr\u00f6mmigkeit um dich herum? Hast du dir schonmal \u00fcberlegt, dass der Gott deiner Freunde, Eltern oder was auch immer dein Gott sein k\u00f6nnte und du dich selbst f\u00fcr oder gegen ihn entscheiden musst? Denn nirgendwo in der Bibel steht, dass Gott Grosskinder hat. Er hat nur Kinder. Vielleicht geh\u00f6rst du aber auch zu denen, welche ihre Distanz zu Gott auf das H\u00f6rensagen von anderen Menschen abst\u00fctzen. Denn so h\u00f6rt man h\u00e4ufig, gibt es heutzutage keinen Grund mehr an einen Gott zu glauben. Weshalb glaubst du nicht? Aus eigener \u00dcberzeugung oder vom H\u00f6rensagen?<br \/>\nWenn wir uns die Reaktion von Jakob vor Augen malen, dann hat dies wenig mit unserer Reaktion auf den Gottesdienst zu tun. Denn Jakob erschauerte angesichts Gottes Gegenwart und seines Traumes. Im hebr\u00e4ischen Urtext steht hier f\u00fcr heilig ein Wort, welches eigentlich nicht heilig bedeutet. Dort steht das Wort \u00abyr&#8217;\u00bb. Was so viel bedeutet wie sich f\u00fcrchten. So steht denn auch in den meisten \u00dcbersetzungen hier anstatt heilig f\u00fcrchten. Doch die \u00dcbersetzung mit heilig ist ebenso richtig. So wird das hebr\u00e4ische Wort insgesamt f\u00fcnf Mal mit heilig wiedergegeben. Heilig und furchteinfl\u00f6ssend liegen nahe beieinander. So wird dies auch in unserem Teaser deutlich, wenn die Worte wiedergegeben werden, welche Mose am brennenden Dornbusch h\u00f6rte. Das Heilige, als etwas abgesondertes, nicht von dieser Welt, hat etwas furchteinfl\u00f6ssendes. Dies zeigt sich durchwegs in der Bibel, dann wenn sich Gott den Menschen zeigt, ist dies nichts f\u00fcr schwache Herzen.<br \/>\nGottesfurcht f\u00fchrt zu Gottesdienst in Ehrfurcht<br \/>\nIn der Theologie spricht man hier von Gottesfurcht. Diese bezeichnet die Haltung gegen\u00fcber Gott und seinem Willen. Aber Gottesfurcht hat nichts mit Furcht im Sinne von Schrecken oder mit Einsch\u00fcchterung zu tun. \u00abDie Furcht des HERRN ist der Anfang der Erkenntnis. [\u2026]\u00bb (Spr\u00fcche 1,7 LUT). Die Gottesfurcht kann m.E. als die Erkenntnis angesehen werden, dass Gott und wir Menschen nicht gleich sind. Gott ist gr\u00f6sser, st\u00e4rker, erhabener und deshalb trete ich in Ehrfurcht vor ihn.<br \/>\nDoch wie ging Jakob mit dieser Erkenntnis um? Fr\u00fch am Morgen stand er auf und stellte sein steinernes Kopfkissen als Erinnerungszeichen auf. Er goss \u00d6l dar\u00fcber und nannte den Ort Bethel. Das heisst Haus Gottes. Danach versprach er Gott, dass wenn er ihn beh\u00fctet auf dem Weg, ihm Essen und Kleider gibt, dann gibt er ihm den zehnten Teil von allem, was er hat. Dies gibt er als Dank f\u00fcr seine F\u00fcrsorge. Jakob sagt nicht, dass er Gott einen Teil von allem gibt, wenn er das Land hat und die Familie. Sondern er gibt ihm alles, wenn Gott ihn beh\u00fctet und er gen\u00fcgend zu essen und Kleider hat &#8211; mehr nicht. Durch die Begegnung mit dem heiligen Gott ist Jakob mit viel weniger zufrieden. Hatte er doch noch ein paar Momente vorher seinen Bruder betrogen, um gesegnet zu sein.<br \/>\nSp\u00e4ter in der Geschichte von Jakob wird sich zeigen, dass Gott treu ist und sein Versprechen an Jakob h\u00e4lt. So h\u00e4lt auch er sein Versprechen. Gott ist heute immer noch der gleiche. Auch heute h\u00e4lt er seine Versprechen. Doch \u00e4hnlich wie sich beim Segen der Fokus weg von irdischen Dingen verschoben hat, so sind auch die Versprechen, welche Jesus Christus uns macht anders. Denn Jesus Christus verheisst seinen Nachfolgern nicht, dass der Glaube immer gl\u00fccklich, reich, sch\u00f6n macht und immer alles einfach ist. So war ja das Leben eines Jakobs auch \u00fcberhaupt nicht geradlinig. So verheisst uns Jesus Christus: \u00ab[\u2026] Wenn einer von euch mit mir gehen will, muss er sich selbst verleugnen, jeden Tag aufs Neue sein Kreuz auf sich nehmen und mir nachfolgen\u00bb (Lukas 9,23 NLB). Auch bei Jesus finden wir die Gottesfurcht. Denn im Angesicht Gottes verliert sogar der Tod seine angsteinfl\u00f6ssende Macht. \u00abHabt keine Angst vor denen, die euch umbringen wollen. Sie k\u00f6nnen nur euren K\u00f6rper t\u00f6ten; eure Seele ist f\u00fcr sie unerreichbar. F\u00fcrchtet allein Gott, der Leib und Seele in der H\u00f6lle vernichten kann\u00bb (Matth\u00e4us 10,28 NLB).<br \/>\nDoch die Gottesfurcht soll uns noch heute in einen Gottesdienst in Ehrfurcht f\u00fchren. So wie dies auch bei Jakob der Fall war. Jakob f\u00fcrchtete sich vor Gott und stellte als Erinnerung an seine Begegnung einen Stein zur Erinnerung auf. Doch die Gottesfurcht f\u00fchrte bei Jakob nicht zu Distanz zu Gott, sondern sie f\u00fchrte zu einer grossen N\u00e4he. Als Jakob einige Jahre sp\u00e4ter eine Familie hatte, l\u00f6ste er sein Versprechen ein. Er opferte diesem Gott, der ihm begegnet war vor der R\u00fcckkehr in sein Heimatland (1. Mose 31,54). Als er diesen Ort seiner Gottesbegegnung erreichte, errichtete er einen richtigen Altar und dr\u00fcckte dadurch seine Verbundenheit zu Gott aus (1. Mose 35,7).<br \/>\nAn diesem Ort Bethel erlebte Jakob beides. Zum einen eine tiefe Intimit\u00e4t mit Gott und zum anderen eine grosse Gottesfurcht. Beides m\u00fcndet schlussendlich in der Ehrfurcht vor Gott. Ehrfurcht bedeutet eine mit Verehrung einhergehende Furcht. Dabei ist der Adressat, vor dem jemand Ehrfurcht hat, immer ein \u00fcberm\u00e4chtiger Adressat. Als Nachfolger von Jesus Christus ist dieser Adressat Gott. Es ist Gott &#8211; der ganz andere. Dabei k\u00f6nnen wir ihn nie vollkommen ergr\u00fcnden. So ist denn auch das sich Befassen mit ihm einerseits wohltuend, andererseits furchteinfl\u00f6ssend. Dies zeigt der Teaser zu unserem Jahresthema sehr deutlich. Daher sollen wir ehrf\u00fcrchtig vor ihn treten und ihn anbeten.<br \/>\nM\u00f6gliche Fragen f\u00fcr die Kleingruppe<br \/>\nBibeltext lesen: 1. Mose 28,10-22<\/p>\n<p>\tVergegenw\u00e4rtige dir erneut die Geschichte von Jakob. Was f\u00e4llt dir neu auf?<br \/>\n\tIst dir Gott bereits begegnet? Wie sah dies aus? Wie war deine Antwort auf diese Begegnung? Wenn dies nicht der Fall ist. Kennst du Gott nur vom H\u00f6rensagen? Wie sieht dieses \u00abKennen\u00bb aus?<br \/>\n\tVerstehst du die Hochhaltung des Z\u00f6libats &#8211; des Lebens als Single zur Ehre Gottes? Was ist der Gewinn eines solchen Lebens? Wie k\u00f6nnen wir aber dazu beitragen, dass die seetal chile immer mehr zu einer Familie wird?<br \/>\n\tWie deutest du f\u00fcr dich die N\u00e4he von \u00abheilig\u00bb und \u00abf\u00fcrchten\u00bb?<br \/>\n\tKennst du Gottesfurcht in deinem Leben? Wie sieht diese bei dir aus?<br \/>\n\tWie k\u00f6nnte es aussehen, einen pers\u00f6nlichen Gottesdienst aus der Gottesfurcht hinaus zu leben, welcher in Ehrfurcht m\u00fcndet?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous ne pou\u00advons pas forcer les ren\u00adcon\u00adtres avec le Dieu saint. Mais si nous le ren\u00adcon\u00adtrons, cela peut par\u00adfois \u00eatre effra\u00adyant. Cepen\u00addant, nous ne devons pas avoir peur de ce Dieu. Car si nous uti\u00adli\u00adsons cet\u00adte peur cor\u00adrec\u00adte\u00adment, elle nous con\u00adduit \u00e0 la crain\u00adte de Dieu. Cel\u00adle-ci nous con\u00adduit \u00e0 son tour \u00e0 un ser\u00advice de Dieu dans la crain\u00adte,&nbsp;comme\u2026<\/p>","protected":false},"author":23,"featured_media":7177,"comment_status":"closed","ping_status":"closed","template":"","wpfc_preacher":[79],"wpfc_sermon_series":[90],"wpfc_sermon_topics":[],"wpfc_bible_book":[],"wpfc_service_type":[12],"class_list":["wpfc_preacher-cedric-bruegger","wpfc_sermon_series-heilig-heilig-heilig","wpfc-sermon-single","post-7170","wpfc_sermon","type-wpfc_sermon","status-publish","has-post-thumbnail","hentry","wpfc_service_type-gottesdienst"],"acf":[],"sermons_blog_filters_topics":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortTopics\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_sermon_topics\"\n\t\t\t\t\t\t\ttitle=\"Sujet\"\n\t\t\t\t\t\t\tid=\"wpfc_sermon_topics\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Sujet<\/option>\n\t\t\t\t\t\t<option value=\"freude\" >Freude<\/option><option value=\"heiliger-geist\" >Heiliger Geist<\/option><option value=\"hoffnung\" >Hoffnung<\/option><option value=\"liebe\" >Liebe<\/option><option value=\"pfingsten\" >Pfingsten<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_series":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortSeries\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_sermon_series\"\n\t\t\t\t\t\t\ttitle=\"S\u00e9ries\"\n\t\t\t\t\t\t\tid=\"wpfc_sermon_series\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">S\u00e9ries<\/option>\n\t\t\t\t\t\t<option value=\"abentueuer-gebaet\" >Abent\u00fc\u00fcr Geb\u00e4t<\/option><option value=\"advent-2019\" >Advent 2019<\/option><option value=\"bestseller-die-bibel\" >Bestseller - Die Bibel<\/option><option value=\"connected\" >connected<\/option><option value=\"creatio\" >CREATIO<\/option><option value=\"eifach-muetig\" >EIFACH muetig \u2013 mit Jesus als Vorbild<\/option><option value=\"einfach-leise-gegenwaertig\" >Einfach. Leise. Gegenw\u00e4rtig.<\/option><option value=\"folge-du-mir-nach\" >Folge du mir nach<\/option><option value=\"glow\" >glow<\/option><option value=\"heilig-heilig-heilig\" >Heilig - Heilig - Heilig<\/option><option value=\"metamorphose\" >Metamorphose<\/option><option value=\"reformation\" >Reformation<\/option><option value=\"seetal-chile-talk\" >seetal chile Talk<\/option><option value=\"teens-segnung\" >Teens Segnung<\/option><option value=\"weitsicht\" >Weitsicht<\/option><option value=\"wie-du-und-ich\" >Wie du und ich<\/option><option value=\"willkommen-daheim\" >Willkommen daheim<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_preachers":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\n\t\t\t\t\t<div class=\"sortPreacher\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_preacher\"\n\t\t\t\t\t\t\ttitle=\"Pr\u00e9dicateur\"\n\t\t\t\t\t\t\tid=\"wpfc_preacher\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Pr\u00e9dicateur<\/option>\n\t\t\t\t\t\t<option value=\"amin-afsharnaderi\" >Amin Afsharnaderi<\/option><option value=\"amir-khalid\" >Amir Khalid<\/option><option value=\"andre-heiniger\" >Andr\u00e9 Heiniger<\/option><option value=\"andreas-jakob\" >Andreas Jakob<\/option><option value=\"ansgar-gmuer\" >Ansgar Gm\u00fcr<\/option><option value=\"barbara-benz\" >Barbara Benz<\/option><option value=\"beat-ungricht\" >Beat Ungricht<\/option><option value=\"beati-forster\" >Beati Forster<\/option><option value=\"beni-leuenberger\" >Beni Leuenberger<\/option><option value=\"bernhard-hohl\" >Bernhard Hohl<\/option><option value=\"cedric-bruegger\" >C\u00e9dric Br\u00fcgger<\/option><option value=\"christian-haslebacher\" >Christian Haslebacher<\/option><option value=\"christian-seitz\" >Christian Seitz<\/option><option value=\"christoph-kunz\" >Christoph Kunz<\/option><option value=\"corinne-jost\" >Corinne Jost<\/option><option value=\"cornelia-roth\" >Cornelia Roth<\/option><option value=\"daniel-bieri\" >Daniel Bieri<\/option><option value=\"debora-sommer\" >Debora Sommer<\/option><option value=\"erich-hunziker\" >Erich Hunziker<\/option><option value=\"esther-wehrli\" >Esther Wehrli<\/option><option value=\"florian-glaser\" >Florian Glaser<\/option><option value=\"gaby-wentland\" >Gaby Wentland<\/option><option value=\"hans-doessegger\" >Hans D\u00f6ssegger<\/option><option value=\"harry-graf\" >Harry Graf<\/option><option value=\"ina-von-schoultz\" >Ina von Schoultz<\/option><option value=\"jan-timon-beck\" >Jan-Timon Beck<\/option><option value=\"john-ghanim\" >John Ghanim<\/option><option value=\"jonas-hauser\" >Jonas Hauser<\/option><option value=\"juergen-will\" >J\u00fcrgen Will<\/option><option value=\"markus-inaebnit\" >Markus In\u00e4bnit<\/option><option value=\"martin-dreyer\" >Martin Dreyer<\/option><option value=\"martin-kiener\" >Martin Kiener<\/option><option value=\"matthias-altwegg\" >Matthias Altwegg<\/option><option value=\"michael-bont\" >Michael Bont<\/option><option value=\"mohanathas-balasubramaniam\" >Mohanathas Balasubramaniam<\/option><option value=\"nathalie-schertenleib\" >Nathalie Schertenleib<\/option><option value=\"peter-inaebnit\" >Peter In\u00e4bnit<\/option><option value=\"peter-michel\" >Peter Michel<\/option><option value=\"rene-winkler\" >Ren\u00e9 Winkler<\/option><option value=\"roger-sigg\" >Roger Sigg<\/option><option value=\"simon-wick\" >Simon Wick<\/option><option value=\"stefan-schuepbach\" >Stefan Sch\u00fcpbach<\/option><option value=\"stephan-bolliger\" >Stephan Bolliger<\/option><option value=\"susanne-geske\" >Susanne Geske<\/option><option value=\"tabea-inaebnit\" >Tabea In\u00e4bnit<\/option><option value=\"thomas-grieve\" >Thomas Grieve<\/option><option value=\"tina-schmidt\" >Tina Schmidt<\/option><option value=\"werner-messmer\" >Werner Messmer<\/option><option value=\"wieland-mueller\" >Wieland M\u00fcller<\/option><option value=\"yanick-buehler\" >Yanick B\u00fchler<\/option><option value=\"yassir-eric\" >Yassir Eric<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_books":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortBooks\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_bible_book\"\n\t\t\t\t\t\t\ttitle=\"Livre\"\n\t\t\t\t\t\t\tid=\"wpfc_bible_book\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Livre<\/option>\n\t\t\t\t\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_service_types":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortServiceTypes\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_service_type\"\n\t\t\t\t\t\t\ttitle=\"Type De Service\"\n\t\t\t\t\t\t\tid=\"wpfc_service_type\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Type De Service<\/option>\n\t\t\t\t\t\t<option value=\"glow-celebration\" >glow Celebration<\/option><option value=\"gottesdienst\" >Gottesdienst<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_filters_dates":"\t\t\t\t<div class=\"sm-filtering\">\n\t\t\t\t\t<div id=\"wpfc_sermon_sorting\" class=\"no-spacing\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"sortDates\" style=\"display: inline-block\">\n\t\t\t\t<form action=\"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/\" method=\"get\">\n\t\t\t\t\t<select name=\"wpfc_dates\"\n\t\t\t\t\t\t\ttitle=\"Date\"\n\t\t\t\t\t\t\tid=\"wpfc_dates\"\n\t\t\t\t\t\t\tonchange=\"if(this.options[this.selectedIndex].value !== ''){return this.form.submit()}else{window.location = window.location.href.split('?')[0];}\"\n\t\t\t\t\t\t\tautocomplete=\"off\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t<option value=\"\">Date<\/option>\n\t\t\t\t\t\t<option value=\"07-2026\" >Jul 2026<\/option><option value=\"06-2026\" >Jun 2026<\/option><option value=\"05-2026\" >May 2026<\/option><option value=\"04-2026\" >Apr 2026<\/option><option value=\"03-2026\" >Mar 2026<\/option><option value=\"02-2026\" >Feb 2026<\/option><option value=\"01-2026\" >Jan 2026<\/option><option value=\"12-2025\" >Dec 2025<\/option><option value=\"11-2025\" >Nov 2025<\/option><option value=\"10-2025\" >Oct 2025<\/option><option value=\"09-2025\" >Sep 2025<\/option><option value=\"08-2025\" >Aug 2025<\/option><option value=\"07-2025\" >Jul 2025<\/option><option value=\"06-2025\" >Jun 2025<\/option><option value=\"05-2025\" >May 2025<\/option><option value=\"04-2025\" >Apr 2025<\/option><option value=\"03-2025\" >Mar 2025<\/option><option value=\"02-2025\" >Feb 2025<\/option><option value=\"01-2025\" >Jan 2025<\/option><option value=\"12-2024\" >Dec 2024<\/option><option value=\"11-2024\" >Nov 2024<\/option><option value=\"10-2024\" >Oct 2024<\/option><option value=\"09-2024\" >Sep 2024<\/option><option value=\"08-2024\" >Aug 2024<\/option><option value=\"07-2024\" >Jul 2024<\/option><option value=\"06-2024\" >Jun 2024<\/option><option value=\"05-2024\" >May 2024<\/option><option value=\"04-2024\" >Apr 2024<\/option><option value=\"03-2024\" >Mar 2024<\/option><option value=\"02-2024\" >Feb 2024<\/option><option value=\"01-2024\" >Jan 2024<\/option><option value=\"12-2023\" >Dec 2023<\/option><option value=\"11-2023\" >Nov 2023<\/option><option value=\"10-2023\" >Oct 2023<\/option><option value=\"09-2023\" >Sep 2023<\/option><option value=\"08-2023\" >Aug 2023<\/option><option value=\"07-2023\" >Jul 2023<\/option><option value=\"06-2023\" >Jun 2023<\/option><option value=\"05-2023\" >May 2023<\/option><option value=\"04-2023\" >Apr 2023<\/option><option value=\"03-2023\" >Mar 2023<\/option><option value=\"02-2023\" >Feb 2023<\/option><option value=\"01-2023\" >Jan 2023<\/option><option value=\"12-2022\" >Dec 2022<\/option><option value=\"11-2022\" >Nov 2022<\/option><option value=\"10-2022\" >Oct 2022<\/option><option value=\"09-2022\" >Sep 2022<\/option><option value=\"08-2022\" >Aug 2022<\/option><option value=\"07-2022\" >Jul 2022<\/option><option value=\"06-2022\" >Jun 2022<\/option><option value=\"05-2022\" >May 2022<\/option><option value=\"04-2022\" >Apr 2022<\/option><option value=\"03-2022\" >Mar 2022<\/option><option value=\"02-2022\" >Feb 2022<\/option><option value=\"01-2022\" >Jan 2022<\/option><option value=\"12-2021\" >Dec 2021<\/option><option value=\"11-2021\" >Nov 2021<\/option><option value=\"10-2021\" >Oct 2021<\/option><option value=\"09-2021\" >Sep 2021<\/option><option value=\"08-2021\" >Aug 2021<\/option><option value=\"07-2021\" >Jul 2021<\/option><option value=\"06-2021\" >Jun 2021<\/option><option value=\"05-2021\" >May 2021<\/option><option value=\"04-2021\" >Apr 2021<\/option><option value=\"03-2021\" >Mar 2021<\/option><option value=\"02-2021\" >Feb 2021<\/option><option value=\"01-2021\" >Jan 2021<\/option><option value=\"12-2020\" >Dec 2020<\/option><option value=\"11-2020\" >Nov 2020<\/option><option value=\"10-2020\" >Oct 2020<\/option><option value=\"09-2020\" >Sep 2020<\/option><option value=\"08-2020\" >Aug 2020<\/option><option value=\"07-2020\" >Jul 2020<\/option><option value=\"06-2020\" >Jun 2020<\/option><option value=\"05-2020\" >May 2020<\/option><option value=\"04-2020\" >Apr 2020<\/option><option value=\"03-2020\" >Mar 2020<\/option><option value=\"02-2020\" >Feb 2020<\/option><option value=\"01-2020\" >Jan 2020<\/option><option value=\"12-2019\" >Dec 2019<\/option><option value=\"11-2019\" >Nov 2019<\/option><option value=\"10-2019\" >Oct 2019<\/option><option value=\"09-2019\" >Sep 2019<\/option><option value=\"08-2019\" >Aug 2019<\/option><option value=\"07-2019\" >Jul 2019<\/option><option value=\"06-2019\" >Jun 2019<\/option><option value=\"05-2019\" >May 2019<\/option><option value=\"04-2019\" >Apr 2019<\/option><option value=\"03-2019\" >Mar 2019<\/option><option value=\"02-2019\" >Feb 2019<\/option><option value=\"01-2019\" >Jan 2019<\/option><option value=\"12-2018\" >Dec 2018<\/option><option value=\"11-2018\" >Nov 2018<\/option><option value=\"10-2018\" >Oct 2018<\/option><option value=\"09-2018\" >Sep 2018<\/option><option value=\"08-2018\" >Aug 2018<\/option><option value=\"07-2018\" >Jul 2018<\/option><option value=\"06-2018\" >Jun 2018<\/option><option value=\"05-2018\" >May 2018<\/option><option value=\"04-2018\" >Apr 2018<\/option><option value=\"03-2018\" >Mar 2018<\/option><option value=\"02-2018\" >Feb 2018<\/option><option value=\"01-2018\" >Jan 2018<\/option><option value=\"12-2017\" >Dec 2017<\/option><option value=\"11-2017\" >Nov 2017<\/option><option value=\"10-2017\" >Oct 2017<\/option><option value=\"09-2017\" >Sep 2017<\/option><option value=\"08-2017\" >Aug 2017<\/option><option value=\"07-2017\" >Jul 2017<\/option><option value=\"06-2017\" >Jun 2017<\/option><option value=\"05-2017\" >May 2017<\/option><option value=\"04-2017\" >Apr 2017<\/option><option value=\"03-2017\" >Mar 2017<\/option><option value=\"02-2017\" >Feb 2017<\/option><option value=\"01-2017\" >Jan 2017<\/option><option value=\"12-2016\" >Dec 2016<\/option><option value=\"11-2016\" >Nov 2016<\/option><option value=\"10-2016\" >Oct 2016<\/option><option value=\"09-2016\" >Sep 2016<\/option><option value=\"08-2016\" >Aug 2016<\/option><option value=\"07-2016\" >Jul 2016<\/option><option value=\"06-2016\" >Jun 2016<\/option><option value=\"05-2016\" >May 2016<\/option><option value=\"04-2016\" >Apr 2016<\/option><option value=\"03-2016\" >Mar 2016<\/option><option value=\"02-2016\" >Feb 2016<\/option><option value=\"01-2016\" >Jan 2016<\/option><option value=\"12-2015\" >Dec 2015<\/option><option value=\"11-2015\" >Nov 2015<\/option><option value=\"10-2015\" >Oct 2015<\/option><option value=\"09-2015\" >Sep 2015<\/option><option value=\"08-2015\" >Aug 2015<\/option><option value=\"07-2015\" >Jul 2015<\/option>\t\t\t\t\t<\/select>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<noscript>\n\t\t\t\t\t\t<div><input type=\"submit\" value=\"Submit\"\/><\/div>\n\t\t\t\t\t<\/noscript>\n\t\t\t\t<\/form>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t","sermons_blog_image_url":"https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/sermons\/2023\/02\/Thumbnail_2023-02-12.jpg","sermons_blog_video":"<video controls preload=\"metadata\" class=\"wpfc-sermon-video-player \" data-plyr_seek='0'><source src=\"https:\/\/youtu.be\/00BIV_dfxvY\"><\/video>","sermons_blog_series":"<a href=\"https:\/\/sermons.seetal-chile.ch\/fr\/series\/heilig-heilig-heilig\/\" rel=\"tag\">Heilig - Heilig - Heilig<\/a>","sermons_blog_meta_sermon_description":"Wir k\u00f6nnen die Begegnungen mit dem heiligen Gott nicht erzwingen. Wenn wir ihm aber begegnen, dann kann dies mitunter furchteinfl\u00f6ssend sein. Dennoch m\u00fcssen wir uns aber vor diesem Gott nicht\u2026","sermons_blog_show_readmore":true,"sermons_blog_audio":"<audio controls preload=\"metadata\" class=\"wpfc-sermon-player \" ><source src=\"https:\/\/resources.seetal-chile.ch\/files\/predigten\/mp3\/predigt_230212.mp3\" type=\"audio\/mp3\"><\/audio>","sermons_blog_preacher_image":"<a href=\"https:\/\/sermons.seetal-chile.ch\/fr\/pr\u00e9dicateur\/cedric-bruegger\/\"><img width=\"150\" height=\"150\" src=\"https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger-150x150.jpg 150w, https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger-300x300.jpg 300w, https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger-1024x1024.jpg 1024w, https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger-768x768.jpg 768w, https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger-1536x1536.jpg 1536w, https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger-75x75.jpg 75w, https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/2022\/02\/Redner_Cedric_Bruegger.jpg 2000w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>","sermons_blog_preacher":"<a href=\"https:\/\/sermons.seetal-chile.ch\/fr\/pr\u00e9dicateur\/cedric-bruegger\/\" rel=\"tag\">C\u00e9dric Br\u00fcgger<\/a>","sermons_blog_bible_passage":"1. Mose 28,17","sermons_blog_service_type":"<a href=\"https:\/\/sermons.seetal-chile.ch\/fr\/type-de-service\/gottesdienst\/\" rel=\"tag\">Gottesdienst<\/a>","sermon_audio":"https:\/\/resources.seetal-chile.ch\/files\/predigten\/mp3\/predigt_230212.mp3","sermon_audio_duration":"","_views":"9728","bible_passage":"1. Mose 28,17","sermon_video_embed":"","sermon_video_url":"https:\/\/youtu.be\/00BIV_dfxvY","sermon_bulletin":"","_featured_url":"https:\/\/sermons.seetal-chile.ch\/wp-content\/uploads\/sermons\/2023\/02\/Thumbnail_2023-02-12.jpg","sermon_date":1676191548,"_sermon_date_auto":false,"_links":{"self":[{"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon"}],"about":[{"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/types\/wpfc_sermon"}],"author":[{"embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/comments?post=7170"}],"version-history":[{"count":5,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/revisions"}],"predecessor-version":[{"id":7175,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon\/7170\/revisions\/7175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/media\/7177"}],"wp:attachment":[{"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/media?parent=7170"}],"wp:term":[{"taxonomy":"wpfc_preacher","embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_preacher?post=7170"},{"taxonomy":"wpfc_sermon_series","embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon_series?post=7170"},{"taxonomy":"wpfc_sermon_topics","embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_sermon_topics?post=7170"},{"taxonomy":"wpfc_bible_book","embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_bible_book?post=7170"},{"taxonomy":"wpfc_service_type","embeddable":true,"href":"https:\/\/sermons.seetal-chile.ch\/fr\/wp-json\/wp\/v2\/wpfc_service_type?post=7170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}